{"id":12798,"date":"2025-05-12T12:53:03","date_gmt":"2025-05-12T10:53:03","guid":{"rendered":"https:\/\/trailrunadvisor.com\/lotteria-hardrock-2026-capire-il-sistema\/"},"modified":"2026-05-10T16:20:13","modified_gmt":"2026-05-10T14:20:13","slug":"lotteria-hardrock-2026-capire-il-sistema","status":"publish","type":"post","link":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/","title":{"rendered":"Lotteria Hardrock 2026 &#8211; Capire il sistema"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12798\" class=\"elementor elementor-12798 elementor-11251\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0134ae5 e-flex e-con-boxed e-con e-parent\" data-id=\"0134ae5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf20ba elementor-widget elementor-widget-image\" data-id=\"ecf20ba\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"720\" src=\"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png\" class=\"attachment-full size-full wp-image-11278\" alt=\"Hardrock lottery\" srcset=\"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png 1080w, https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7-300x200.png 300w, https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7-1024x683.png 1024w, https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7-768x512.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323388c elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"323388c\" data-element_type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Lotteria Hardrock 2026 &#8211; Capire il sistema<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4329d3c elementor-align-center elementor-widget elementor-widget-post-info\" data-id=\"4329d3c\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-2adc81a elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Maggio 12, 2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b670636 elementor-widget elementor-widget-text-editor\" data-id=\"b670636\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La <\/span><b>Lotteria Hardrock<\/b><span style=\"font-weight: 400;\">  \u00e8 una bestia a s\u00e9 stante. Come corridore che ha finalmente sentito il mio nome estratto dopo anni di tentativi, voglio condividere ci\u00f2 che ho imparato, non solo sul processo in s\u00e9 ma anche su come   <\/span><b>accatastare le probabilit\u00e0<\/b><span style=\"font-weight: 400;\">  (e biglietti) a tuo favore. Non si tratta solo di una ripartizione tecnica, ma anche di un&#8217;analisi dei costi di gestione.   <\/span><a href=\"https:\/\/www.instagram.com\/trailrunadvisor\/\"><span style=\"font-weight: 400;\">la storia <\/span><\/a><span style=\"font-weight: 400;\">di grinta, strategia e comunit\u00e0, il tutto in una delle lotterie ultra pi\u00f9 difficili in circolazione.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be206ba elementor-widget elementor-widget-heading\" data-id=\"be206ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il mio primo incontro con la Lotteria Hardrock\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da422ad elementor-widget elementor-widget-text-editor\" data-id=\"da422ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nel 2018 ho visto un video della Hardrock 100 e ho capito subito che un giorno avrei dovuto correrla. Il terreno, l&#8217;altitudine, il senso di cameratismo&#8230; mi hanno colpito. Ma i miei sogni si sono subito scontrati con la realt\u00e0: questa gara non richiede solo gambe, ma anche pazienza, perseveranza e un tipo di pianificazione molto particolare.  <\/span><\/p><p><span style=\"font-weight: 400;\">La <\/span><b>Lotteria Hardrock<\/b><span style=\"font-weight: 400;\">  Il sistema non \u00e8 semplice come quello di altre gare. Ci sono standard di qualificazione, un sistema di biglietteria ponderato e categorie specifiche che dividono i corridori in gruppi. Capire queste sfumature \u00e8 stato il mio primo passo verso un impegno pluriennale che alla fine mi avrebbe ripagato con la 100 miglia pi\u00f9 gratificante della mia vita.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ddb33f elementor-widget elementor-widget-heading\" data-id=\"9ddb33f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il sistema di pool a tre lotterie: Conosci la tua categoria<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-589cb36 elementor-widget elementor-widget-text-editor\" data-id=\"589cb36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per dare a tutti una possibilit\u00e0 equa e allo stesso tempo premiare la fedelt\u00e0, la lotteria Hardrock \u00e8 divisa in tre gruppi separati:<\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Mai iniziati<\/b><span style=\"font-weight: 400;\"> (coloro che non hanno mai corso ad Hardrock),<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Veterani<\/b><span style=\"font-weight: 400;\"> (coloro che si sono classificati cinque o pi\u00f9 volte),<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tutti gli altri<\/b><span style=\"font-weight: 400;\"> (coloro che l&#8217;hanno eseguito da una a quattro volte).<\/span><\/li><\/ol><p><span style=\"font-weight: 400;\">Dato che ero un nuovo arrivato, ho partecipato alla pool \u201cNever Starters\u201d. Questo significava un numero inferiore di slot complessivi e una forte concorrenza.  Il  <\/span><b>La lotteria di Hardrock<\/b><span style=\"font-weight: 400;\"> Il numero totale di corridori \u00e8 limitato a 145 (soggetto a variazioni a seconda delle condizioni della neve e dei permessi), quindi ogni posto \u00e8 importante ed \u00e8 ferocemente conteso.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1733f25 elementor-widget elementor-widget-heading\" data-id=\"1733f25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Moltiplicazione dei biglietti: L'effetto palla di neve\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4238004 elementor-widget elementor-widget-text-editor\" data-id=\"4238004\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Uno degli elementi pi\u00f9 strategici della <\/span><b>lotteria Hardrock<\/b><span style=\"font-weight: 400;\">  \u00e8 il suo sistema di biglietti ponderati. Ogni anno che ti qualifichi e non vieni scelto, il tuo numero di biglietti aumenta esponenzialmente. Funziona cos\u00ec:  <\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anno 1: 1 biglietto<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anno 2: 2 biglietti<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anno 3: 4 biglietti<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anno 4: 8 biglietti<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">E cos\u00ec via&#8230;<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Questo sistema di capitalizzazione premia la costanza. Al quinto tentativo, avevo 16 biglietti in estrazione. Questo ha cambiato le carte in tavola. Mentre alcuni sono fortunati con un solo biglietto, le probabilit\u00e0 migliorano drasticamente con il tempo e la disciplina.   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f12749d elementor-widget elementor-widget-heading\" data-id=\"f12749d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Consigli utili: Non perdere mai un anno di qualifica\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0e258f elementor-widget elementor-widget-text-editor\" data-id=\"b0e258f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Se potessi darti un solo consiglio, sarebbe questo: <\/span><b>non saltare mai una gara di qualificazione<\/b><span style=\"font-weight: 400;\">. Se lo fai, il tuo conteggio dei biglietti si azzera. Ho rischiato di commettere questo errore nel 2021, quando un infortunio mi ha tenuto lontano dai piedi per mesi. Fortunatamente mi sono dedicato a compiti di pacing e sono guarito in tempo per partecipare a una gara di qualificazione di fine stagione.  <\/span><\/p><p><span style=\"font-weight: 400;\">La posta in gioco \u00e8 alta. Un anno di pausa potrebbe significare altri cinque anni di tentativi. Quindi scegli la tua qualificazione in anticipo, pianifica la tua stagione in base ad essa e portala a termine, senza scuse.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5d6809 elementor-widget elementor-widget-heading\" data-id=\"b5d6809\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gare di qualificazione: Scegli con saggezza\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6acbe48 elementor-widget elementor-widget-text-editor\" data-id=\"6acbe48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per partecipare alla <\/span><b>Lotteria Hardrock<\/b><span style=\"font-weight: 400;\">devi completare una gara di qualificazione designata entro la finestra di eleggibilit\u00e0. Non si tratta di una normale gara da 100 km. Sono state scelte per rispecchiare la sfida di Hardrock: alta quota, terreno remoto e dislivello significativo.  <\/span><\/p><p><span style=\"font-weight: 400;\">Personalmente ho scelto il <\/span><a href=\"https:\/\/trailrunadvisor.com\/races\/tor-des-geants\/\"><span style=\"font-weight: 400;\">Tor des G\u00e9ants<\/span><\/a><span style=\"font-weight: 400;\">  e la Bighorn 100 ad anni alterni. Entrambe hanno offerto quello che io chiamo \u201callenamento Hardrock sotto mentite spoglie\u201d. Ogni corsa mi ha reso pi\u00f9 forte, mi ha insegnato a gestire condizioni brutali e mi ha aiutato ad aumentare la mia scorta di biglietti.  <\/span><\/p><p><span style=\"font-weight: 400;\">Troverai l \u201celenco completo sul sito web di Hardrock, ma non limitarti alla vicinanza o alla convenienza. Considera fattori come l\u201d orario di partenza, il tempo e il modo in cui la gara si inserisce nel tuo calendario personale. E se puoi, scegli una gara a cui ti piacer\u00e0 tornare anno dopo anno, perch\u00e9 probabilmente lo farai.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2381e elementor-widget elementor-widget-heading\" data-id=\"de2381e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Volontariato e comunit\u00e0: Pi\u00f9 che un semplice karma positivo\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-619f73b elementor-widget elementor-widget-text-editor\" data-id=\"619f73b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Un consiglio spesso trascurato \u00e8 quello di partecipare alla comunit\u00e0 di Hardrock. <\/span><b>comunit\u00e0 Hardrock<\/b><span style=\"font-weight: 400;\">. Sebbene il volontariato non aggiunga direttamente biglietti (come in altre gare ultras), ti mette in contatto con i direttori di gara, i corridori passati e altri aspiranti. Ho passato due estati a fare il volontario al Kroger&#8217;s Canteen, probabilmente la stazione di rifornimento pi\u00f9 iconica del percorso. <\/span><\/p><p><span style=\"font-weight: 400;\">Questo mi ha permesso di vedere in prima fila la magia dell&#8217;Hardrock. Ho visto come le persone si muovevano, come si rifornivano di carburante, come si rompevano e come continuavano ad andare avanti. Mi ha anche ricordato perch\u00e9 ero disposta ad aspettare anni per raggiungere quella linea. Questi momenti mi hanno mantenuto motivato durante anni di sofferenza senza lotteria.   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78bb2e4 elementor-widget elementor-widget-heading\" data-id=\"78bb2e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pacing e crewing: Impara il percorso da bordo campo\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6504876 elementor-widget elementor-widget-text-editor\" data-id=\"6504876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L&#8217;anno prima di essere sorteggiata, ho seguito un amico per le ultime 40 miglia. Quell&#8217;esperienza \u00e8 stata preziosa. Non solo mi sono fatto un&#8217;idea del tratto notturno e della fatica mentale, ma ho anche appreso nozioni pratiche come le fonti d&#8217;acqua, la strategia di pacing e il timing dell&#8217;alimentazione in condizioni reali di Hardrock.  <\/span><\/p><p><span style=\"font-weight: 400;\">Se hai la possibilit\u00e0 di fare il passo, approfittane. \u00c8 la cosa pi\u00f9 simile a correre la gara senza correrla davvero. E quando finalmente verr\u00e0 fuori il tuo nome, potrai tagliare il traguardo con fiducia invece che con cieca speranza.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63a32ba elementor-widget elementor-widget-heading\" data-id=\"63a32ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quanto tempo devi aspettare?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d041d elementor-widget elementor-widget-text-editor\" data-id=\"16d041d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questa \u00e8 la domanda che tutti si pongono e purtroppo non c&#8217;\u00e8 una risposta facile. I calcoli variano in base al tuo gruppo, al numero di biglietti e al caso. Ho conosciuto corridori che sono stati ammessi al primo tentativo e altri che hanno aspettato pi\u00f9 di dieci anni.  <\/span><\/p><p><span style=\"font-weight: 400;\">Personalmente, sono stato estratto al sesto tentativo con 16 biglietti. Questo mi ha fatto superare la media, ma non di molto. Se sei costante, sano e strategico, aspettati una durata compresa tra i 5 e gli 8 anni. \u00c8 doloroso, certo. Ma credimi, ne vale la pena ogni secondo.    <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9010e8 elementor-widget elementor-widget-heading\" data-id=\"e9010e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La mentalit\u00e0 \u201cOgni anno conta\u201d\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74dc005 elementor-widget elementor-widget-text-editor\" data-id=\"74dc005\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quando inizi ad accumulare biglietti, sei tentato di dire: \u201cFar\u00f2 sul serio tra qualche anno\u201d. Non farlo. Ogni anno di ritardo \u00e8 un anno in pi\u00f9 che passerai ad aspettare. Ho trattato ogni biglietto come se fosse oro. Ho pianificato le mie gare con un anno di anticipo, ho prenotato i viaggi in anticipo e ho tenuto sotto controllo gli infortuni con un allenamento intelligente.    <\/span><\/p><p><span style=\"font-weight: 400;\">Questa mentalit\u00e0 di gioco a lungo termine ha trasformato il mio approccio all \u201cultrarunning. Invece di passare da una gara all\u201d altra per divertimento, mi sono concentrato. Ho costruito forza, resilienza e strumenti mentali che ho utilizzato il giorno della gara. Il sistema dei biglietti non \u00e8 solo un modo per partecipare alla gara: \u00e8 una filosofia di allenamento.   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61ccc3c elementor-widget elementor-widget-heading\" data-id=\"61ccc3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Evitare la squalifica: Leggi le regole\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad4ca2b elementor-widget elementor-widget-text-editor\" data-id=\"ad4ca2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Un anno, un mio amico ha perso tutti i biglietti accumulati a causa di un semplice malinteso: non si era reso conto che la sua qualificazione doveva avvenire all \u201cinterno della specifica finestra dell\u201d anno di gara. Ha corso la gara giusta, solo due settimane prima. Questa svista gli \u00e8 costata cinque anni di progressi.  <\/span><\/p><p><span style=\"font-weight: 400;\">Prima di inviare la tua iscrizione, leggi la pagina delle qualifiche. Poi rileggila. Assicurati che la tua gara sia presente nell&#8217;elenco, che rientri nelle date giuste e che sia stata completata entro i termini previsti. Non dare per scontato. Verifica.    <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-324456d elementor-widget elementor-widget-heading\" data-id=\"324456d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rimanere impegnati senza esaurirsi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7240125 elementor-widget elementor-widget-text-editor\" data-id=\"7240125\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dopo alcuni anni di rifiuti, \u00e8 facile amareggiarsi o disinteressarsi. Ho rischiato di staccare la spina al quarto anno. Ma invece di mollare, ho trovato il modo di continuare a impegnarmi. Ho fatto di Hardrock la mia \u201cstella polare\u201d e ho usato il viaggio come motivo per esplorare altre gare straordinarie.   <\/span><\/p><p><span style=\"font-weight: 400;\">Ho corso Wasatch, San Juan Solstice e ho anche esplorato alternative europee come l&#8217;Eiger Ultra Trail. Ogni avventura mi ha dato gioia, ha tenuto le mie gambe pronte e ha mantenuto il mio legame emotivo con le montagne. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-814e56b elementor-widget elementor-widget-heading\" data-id=\"814e56b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il giorno della gara: Il momento in cui tutto ha avuto senso\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ada7a elementor-widget elementor-widget-text-editor\" data-id=\"f6ada7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quando finalmente sono entrato, la sensazione \u00e8 stata surreale. Ho fissato lo schermo per minuti, ricaricando i risultati della lotteria come se fossero svaniti. Ma la vera magia \u00e8 avvenuta sul sentiero.  <\/span><\/p><p><span style=\"font-weight: 400;\">Ogni biglietto, ogni anno di attesa, ogni barbecue di famiglia perso per allenarsi: tutto si \u00e8 riunito in quell&#8217;anello attraverso i San Juans. Conoscevo le salite. Rispettavo il tempo. Mi sono mosso con sicurezza. E quando ho baciato la roccia al traguardo, ho pianto.    <\/span><\/p><p><span style=\"font-weight: 400;\">Non perch\u00e9 avevo finito Hardrock, ma perch\u00e9 me lo ero guadagnato. Ogni biglietto guadagnato con fatica \u00e8 stato un capitolo di una storia che non dimenticher\u00f2 mai. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5914f4c elementor-widget elementor-widget-heading\" data-id=\"5914f4c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ultimi consigli per ottimizzare la tua strategia di acquisto dei biglietti\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d15dc3d elementor-widget elementor-widget-text-editor\" data-id=\"d15dc3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Per concludere, ecco una lista dei miei migliori consigli pratici:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Scegli il tuo qualificatore in anticipo<\/b><span style=\"font-weight: 400;\">e impegnarsi a farlo. Non \u00e8 il caso di rimuginare in ritardo. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tieni un calendario<\/b><span style=\"font-weight: 400;\"> con le date di iscrizione, le finestre di qualificazione e gli orari di chiusura.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Rimani fedele a una sola categoria<\/b><span style=\"font-weight: 400;\">-Non passare da una categoria all&#8217;altra se non \u00e8 inevitabile.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Evita le lesioni<\/b><span style=\"font-weight: 400;\">  allenandoti in modo intelligente, non solo duro. Fai cross-training e riposa intenzionalmente. <\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Rimani connesso<\/b><span style=\"font-weight: 400;\"> Rimani in contatto con la comunit\u00e0 di Hardrock attraverso i forum, il volontariato e il pacing.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tieni traccia del numero di biglietti<\/b><span style=\"font-weight: 400;\"> ogni anno e ricontrolla la validit\u00e0 del tuo qualificatore.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Trova la gioia nell&#8217;attesa<\/b><span style=\"font-weight: 400;\">-Corri le gare che arricchiscono il tuo viaggio.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a69ddd elementor-widget elementor-widget-heading\" data-id=\"8a69ddd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per concludere: \u00c8 uno stile di vita, non solo una lotteria.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4980cd1 elementor-widget elementor-widget-text-editor\" data-id=\"4980cd1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La <\/span><b>Lotteria Hardrock<\/b><span style=\"font-weight: 400;\">  mi ha insegnato molto di pi\u00f9 di come partecipare a una gara. Mi ha insegnato la pazienza, la pianificazione e ad amare il gioco lungo. Ha plasmato il mio allenamento, le mie amicizie e il mio rapporto con le montagne.  <\/span><\/p><p><span style=\"font-weight: 400;\">Se stai iniziando ora il tuo percorso con i biglietti, abbraccialo. Non inseguire solo un traguardo, ma la persona che diventerai mentre ti guadagni il posto. E un giorno, quando sentirai il tuo nome, capirai che la lotteria non \u00e8 mai stata una questione di fortuna. Si trattava di lealt\u00e0.   <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Lotteria Hardrock \u00e8 una bestia a s\u00e9 stante. Come corridore che ha finalmente sentito il mio nome estratto dopo anni di tentativi, voglio condividere ci\u00f2 che ho imparato, non solo sul processo in s\u00e9 ma anche su come accatastare le probabilit\u00e0 (e biglietti) a tuo favore. Non si tratta solo di una ripartizione tecnica, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"category":[139],"tag":[],"class_list":["post-12798","post","type-post","status-publish","format-standard","hentry","categories-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lotteria Hardrock 2026 - Capire il sistema e gli ultimi pettorali<\/title>\n<meta name=\"description\" content=\"Scopri come aumentare le tue possibilit\u00e0 nella lotteria Hardrock 2026. Suggerimenti per accumulare biglietti, evitare gli errori pi\u00f9 comuni e rimanere motivati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lotteria Hardrock 2026 - Capire il sistema e gli ultimi pettorali\" \/>\n<meta property=\"og:description\" content=\"Scopri come aumentare le tue possibilit\u00e0 nella lotteria Hardrock 2026. Suggerimenti per accumulare biglietti, evitare gli errori pi\u00f9 comuni e rimanere motivati.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/\" \/>\n<meta property=\"og:site_name\" content=\"Trail Run Advisor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61554747731790&amp;mibextid=9R9pXO\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-12T10:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T14:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"iMfwI8uAFh5Q6976rfxj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"iMfwI8uAFh5Q6976rfxj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lotteria Hardrock 2026 - Capire il sistema e gli ultimi pettorali","description":"Scopri come aumentare le tue possibilit\u00e0 nella lotteria Hardrock 2026. Suggerimenti per accumulare biglietti, evitare gli errori pi\u00f9 comuni e rimanere motivati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/","og_locale":"it_IT","og_type":"article","og_title":"Lotteria Hardrock 2026 - Capire il sistema e gli ultimi pettorali","og_description":"Scopri come aumentare le tue possibilit\u00e0 nella lotteria Hardrock 2026. Suggerimenti per accumulare biglietti, evitare gli errori pi\u00f9 comuni e rimanere motivati.","og_url":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/","og_site_name":"Trail Run Advisor","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61554747731790&mibextid=9R9pXO","article_published_time":"2025-05-12T10:53:03+00:00","article_modified_time":"2026-05-10T14:20:13+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png","type":"image\/png"}],"author":"iMfwI8uAFh5Q6976rfxj","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"iMfwI8uAFh5Q6976rfxj","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#article","isPartOf":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/"},"author":{"name":"iMfwI8uAFh5Q6976rfxj","@id":"https:\/\/trailrunadvisor.com\/it\/#\/schema\/person\/3e2010e74dd3c2a21ba9ce2b43d6991d"},"headline":"Lotteria Hardrock 2026 &#8211; Capire il sistema","datePublished":"2025-05-12T10:53:03+00:00","dateModified":"2026-05-10T14:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/"},"wordCount":1681,"publisher":{"@id":"https:\/\/trailrunadvisor.com\/it\/#organization"},"image":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/","url":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/","name":"Lotteria Hardrock 2026 - Capire il sistema e gli ultimi pettorali","isPartOf":{"@id":"https:\/\/trailrunadvisor.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#primaryimage"},"image":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png","datePublished":"2025-05-12T10:53:03+00:00","dateModified":"2026-05-10T14:20:13+00:00","description":"Scopri come aumentare le tue possibilit\u00e0 nella lotteria Hardrock 2026. Suggerimenti per accumulare biglietti, evitare gli errori pi\u00f9 comuni e rimanere motivati.","breadcrumb":{"@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#primaryimage","url":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png","contentUrl":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2025\/05\/may-2025-1080-x-720-px-7.png"},{"@type":"BreadcrumbList","@id":"https:\/\/trailrunadvisor.com\/it\/lotteria-hardrock-2026-capire-il-sistema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trailrunadvisor.com\/it\/"},{"@type":"ListItem","position":2,"name":"Lotteria Hardrock 2026 &#8211; Capire il sistema"}]},{"@type":"WebSite","@id":"https:\/\/trailrunadvisor.com\/it\/#website","url":"https:\/\/trailrunadvisor.com\/it\/","name":"Trail Run Advisor","description":"","publisher":{"@id":"https:\/\/trailrunadvisor.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trailrunadvisor.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/trailrunadvisor.com\/it\/#organization","name":"Trail Run Advisor","url":"https:\/\/trailrunadvisor.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trailrunadvisor.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2023\/12\/logo-trailrunadvisor.png","contentUrl":"https:\/\/trailrunadvisor.com\/wp-content\/uploads\/2023\/12\/logo-trailrunadvisor.png","width":613,"height":80,"caption":"Trail Run Advisor"},"image":{"@id":"https:\/\/trailrunadvisor.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61554747731790&mibextid=9R9pXO","https:\/\/www.instagram.com\/trailrunadvisor\/"]},{"@type":"Person","@id":"https:\/\/trailrunadvisor.com\/it\/#\/schema\/person\/3e2010e74dd3c2a21ba9ce2b43d6991d","name":"iMfwI8uAFh5Q6976rfxj","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/trailrunadvisor.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c6819356538849544fe79abd31afb6f42861bbb96368a1f2151f9a226524dcd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c6819356538849544fe79abd31afb6f42861bbb96368a1f2151f9a226524dcd?s=96&d=mm&r=g","caption":"iMfwI8uAFh5Q6976rfxj"},"sameAs":["https:\/\/trailrunadvisor.com"]}]}},"_links":{"self":[{"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/posts\/12798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/comments?post=12798"}],"version-history":[{"count":2,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/posts\/12798\/revisions"}],"predecessor-version":[{"id":15404,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/posts\/12798\/revisions\/15404"}],"wp:attachment":[{"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/media?parent=12798"}],"wp:term":[{"taxonomy":"categories","embeddable":true,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/category?post=12798"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/trailrunadvisor.com\/it\/wp-json\/wp\/v2\/tag?post=12798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}